{"id":201,"count":2,"description":"","link":"https:\/\/garantiwebdesign.com\/wordpress\/decora\/product-category\/living-room\/triple-seat\/","name":"Triple Seat","slug":"triple-seat","taxonomy":"product_cat","parent":87,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/garantiwebdesign.com\/wordpress\/decora\/wp-json\/wp\/v2\/product_cat\/201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/garantiwebdesign.com\/wordpress\/decora\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/garantiwebdesign.com\/wordpress\/decora\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/garantiwebdesign.com\/wordpress\/decora\/wp-json\/wp\/v2\/product_cat\/87"}],"wp:post_type":[{"href":"https:\/\/garantiwebdesign.com\/wordpress\/decora\/wp-json\/wp\/v2\/product?product_cat=201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}